{"id":863,"date":"2023-12-11T16:37:57","date_gmt":"2023-12-11T15:37:57","guid":{"rendered":"https:\/\/dda.ycomoes.com\/?page_id=863"},"modified":"2023-12-11T16:51:58","modified_gmt":"2023-12-11T15:51:58","slug":"nucleo-el-cercado","status":"publish","type":"page","link":"https:\/\/dda.ycomoes.com\/index.php\/nucleo-el-cercado\/","title":{"rendered":"Nucleo El Cercado"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"863\" class=\"elementor elementor-863\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-975ea69 e-flex e-con-boxed e-con e-parent\" data-id=\"975ea69\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8998bf2 elementor-widget elementor-widget-text-editor\" data-id=\"8998bf2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>&#8220;DIAGNOSTICO DE APRENDIZAJES &#8211; REPORTE DE RESULTADOS&#8221; MATEMATICAS &#8211; LENGUAJE DE 3RO. DE PRIMARIA<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe301fc e-flex e-con-boxed e-con e-parent\" data-id=\"fe301fc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7708221 elementor-widget elementor-widget-accordion\" data-id=\"7708221\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1241\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1241\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comun Pampa<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1241\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1241\"><p style=\"text-align: center;\">Matem\u00e1ticas<\/p><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-870\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/mate-Comun-Pampa-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/mate-Comun-Pampa-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/mate-Comun-Pampa-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/mate-Comun-Pampa-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/mate-Comun-Pampa.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><p style=\"text-align: center;\">Lenguaje<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-868 aligncenter\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Comun-Pampa-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Comun-Pampa-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Comun-Pampa-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Comun-Pampa-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Comun-Pampa.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1242\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1242\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">El Cercado<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1242\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1242\"><p style=\"text-align: center;\">Matem\u00e1ticas<\/p><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-875\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-El-Cercado-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-El-Cercado-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-El-Cercado-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-El-Cercado-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-El-Cercado.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><p style=\"text-align: center;\">\u00a0<\/p><p style=\"text-align: center;\">Lenguaje<\/p><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-874\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-El-Cercado-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-El-Cercado-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-El-Cercado-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-El-Cercado-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-El-Cercado.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><p style=\"text-align: center;\">\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1243\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1243\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Marquilla<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1243\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1243\"><p style=\"text-align: center;\">Matem\u00e1ticas<\/p><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-880\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Marquilla-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Marquilla-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Marquilla-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Marquilla-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Marquilla.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><p>\u00a0<\/p><p style=\"text-align: center;\">Lenguaje<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-879 aligncenter\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Marquilla-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Marquilla-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Marquilla-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Marquilla-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Marquilla.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1244\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1244\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wawa Wawa<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1244\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1244\"><p style=\"text-align: center;\">Matem\u00e1ticas<\/p><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-886\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Wawa-Wawa-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Wawa-Wawa-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Wawa-Wawa-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Wawa-Wawa-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Mate-Wawa-Wawa.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><p style=\"text-align: center;\">\u00a0<\/p><p style=\"text-align: center;\">Lenguaje<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-884 aligncenter\" src=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Wawa-Wawa-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Wawa-Wawa-1024x427.png 1024w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Wawa-Wawa-300x125.png 300w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Wawa-Wawa-768x320.png 768w, https:\/\/dda.ycomoes.com\/wp-content\/uploads\/2023\/12\/Lectura-Wawa-Wawa.png 1311w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&#8220;DIAGNOSTICO DE APRENDIZAJES &#8211; REPORTE DE RESULTADOS&#8221; MATEMATICAS &#8211; LENGUAJE DE 3RO. DE PRIMARIA Comun Pampa Matem\u00e1ticas Lenguaje El Cercado Matem\u00e1ticas \u00a0 Lenguaje \u00a0 Marquilla Matem\u00e1ticas \u00a0 Lenguaje Wawa Wawa Matem\u00e1ticas \u00a0 Lenguaje<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-863","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/pages\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":16,"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/pages\/863\/revisions"}],"predecessor-version":[{"id":889,"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/pages\/863\/revisions\/889"}],"wp:attachment":[{"href":"https:\/\/dda.ycomoes.com\/index.php\/wp-json\/wp\/v2\/media?parent=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}